{"id":11556,"date":"2022-06-19T12:38:34","date_gmt":"2022-06-19T10:38:34","guid":{"rendered":"https:\/\/vomi.de\/?post_type=wpfc_sermon&#038;p=11556"},"modified":"2025-10-10T15:33:42","modified_gmt":"2025-10-10T15:33:42","slug":"dein-weg-in-ein-neues-leben","status":"publish","type":"wpfc_sermon","link":"https:\/\/podcast.hope-kirche.de\/index.php\/sermons\/dein-weg-in-ein-neues-leben\/","title":{"rendered":"Dein Weg in ein neues Leben"},"content":{"rendered":"<p><em>Die biblischen Stories inspirieren uns Menschen auch noch Tausende Jahre sp\u00e4ter, weil wir darin Jesus Christus, uns selber und wie wir mit ihm leben k\u00f6nnen, entdecken. In dieser Predigt h\u00f6rst du die Geschichte des syrischen Kriegshelden Naaman, der allen Erfolg im Leben hatte, aber an einer Krankheit litt, die St\u00fcck f\u00fcr St\u00fcck sein Leben zerst\u00f6rte&#8230; Was k\u00f6nnen wir tun, wenn wir feststellen, dass der Materialismus und unser Ansehen uns nicht das eigentliche Leben mit Gott schenken? Welches \u201eRezept\u201c f\u00fcr ein neues Leben funktioniert? Und wozu fordert es uns pers\u00f6nlich auf und heraus? Dazu h\u00f6rst du mehr in dieser Predigt. \u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die biblischen Stories inspirieren uns Menschen auch noch Tausende Jahre sp\u00e4ter, weil wir darin Jesus Christus, uns selber und wie wir mit ihm leben k\u00f6nnen, entdecken. In dieser Predigt h\u00f6rst du die Geschichte des syrischen Kriegshelden Naaman, der allen Erfolg im Leben hatte, aber an einer Krankheit litt, die St\u00fcck f\u00fcr St\u00fcck sein Leben zerst\u00f6rte&#8230; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11603,"comment_status":"closed","ping_status":"closed","template":"","wpfc_preacher":[220],"wpfc_sermon_series":[],"wpfc_sermon_topics":[],"wpfc_bible_book":[],"wpfc_service_type":[85],"class_list":{"0":"wpfc_preacher-stefan-uhlig","1":"wpfc-sermon-single","2":"post-11556","3":"wpfc_sermon","4":"type-wpfc_sermon","5":"status-publish","6":"has-post-thumbnail","7":"hentry","9":"wpfc_service_type-gottesdienst-sonntagmorgen"},"sermon_audio":"https:\/\/vomi-wordpress-media.s3.eu-central-1.amazonaws.com\/podcast\/2022\/06\/25065810\/19.06.22.mp3","sermon_audio_duration":"00:42:17","_views":"114","bible_passage":"","sermon_video_embed":"","sermon_video_url":"","sermon_bulletin":"","_featured_url":"https:\/\/vomi-wordpress-media.s3.eu-central-1.amazonaws.com\/podcast\/2022\/06\/25065814\/thumbnail_220619_StUh_feed.jpg","sermon_date":1655642314,"_sermon_date_auto":false,"_links":{"self":[{"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/wpfc_sermon\/11556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/wpfc_sermon"}],"about":[{"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/types\/wpfc_sermon"}],"author":[{"embeddable":true,"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/comments?post=11556"}],"version-history":[{"count":1,"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/wpfc_sermon\/11556\/revisions"}],"predecessor-version":[{"id":13897,"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/wpfc_sermon\/11556\/revisions\/13897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/media\/11603"}],"wp:attachment":[{"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/media?parent=11556"}],"wp:term":[{"taxonomy":"wpfc_preacher","embeddable":true,"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/wpfc_preacher?post=11556"},{"taxonomy":"wpfc_sermon_series","embeddable":true,"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/wpfc_sermon_series?post=11556"},{"taxonomy":"wpfc_sermon_topics","embeddable":true,"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/wpfc_sermon_topics?post=11556"},{"taxonomy":"wpfc_bible_book","embeddable":true,"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/wpfc_bible_book?post=11556"},{"taxonomy":"wpfc_service_type","embeddable":true,"href":"https:\/\/podcast.hope-kirche.de\/index.php\/wp-json\/wp\/v2\/wpfc_service_type?post=11556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}